{"id":1068,"date":"2026-07-18T10:17:03","date_gmt":"2026-07-18T10:17:03","guid":{"rendered":"https:\/\/mitribunafutbolera.com\/?p=1068"},"modified":"2026-07-26T17:01:19","modified_gmt":"2026-07-26T17:01:19","slug":"argentina-encomendada-a-su-caracter-y-a-messi","status":"publish","type":"post","link":"https:\/\/mitribunafutbolera.com\/index.php\/2026\/07\/18\/argentina-encomendada-a-su-caracter-y-a-messi\/","title":{"rendered":"Argentina, encomendada a su car\u00e1cter y a Messi"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Llega Argentina a esta final ante Espa\u00f1a habiendo dejado muchas dudas en su juego, pese a haber tenido un camino que se puede considerar como bastante asequible; de hecho, es la primera selecci\u00f3n en la historia de las Copas del Mundo que ha llegado a las semifinales sin haberse enfrentado a ninguna selecci\u00f3n clasificada en el top-10 de la clasificaci\u00f3n FIFA en el momento de disputarse el Mundial. Aunque algunos planteamientos interesados atribuyan este hecho a un supuesto trato de favor a Argentina obedeciendo ciertos intereses, lo cierto es que si Uruguay (siendo segunda en su grupo) y Portugal (ganando el suyo) hubiesen cumplido los pron\u00f3sticos, muy diferente hubiese sido su camino. Sin embargo, pese a este, en teor\u00eda, apacible camino, Argentina ha sufrido bastante m\u00e1s de lo que cabr\u00eda prever y, aunque complet\u00f3 una primera fase inmaculada con tres victorias en otros tantos partidos (Austria, Jordania y Argelia), ha sufrido notablemente en todos los partidos de eliminatorias: se fue a la pr\u00f3rroga con Cabo Verde en dieciseisavos de final (tres a dos fue el marcador final), repiti\u00f3 resultado con Egipto en octavos, tras remontar un uno a dos adverso en los \u00faltimos diez minutos del tiempo reglamentario con cierta pol\u00e9mica arbitral, repiti\u00f3 pr\u00f3rroga ante Suiza en cuartos de final para acabar imponi\u00e9ndose por tres tantos a uno y volvi\u00f3 a remontar en los \u00faltimos diez minutos el tanto inicial de Inglaterra en las semifinales. Pero, agarrados a Messi \u2013 8 goles hasta el momento -, y al car\u00e1cter y a la competitividad del equipo que les lleva a no rendirse hasta el \u00faltimo segundo, han llegado a disputar su segunda final de Copa del Mundo consecutiva y poder defender, as\u00ed, el t\u00edtulo logrado en Catar \u20182022.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Y, tomando como referencia este \u00faltimo Mundial y viendo las similitudes y diferencias con el equipo actual, podemos empezar a comprender las dificultades que ha ido enfrentando Argentina en la presente edici\u00f3n. Si miramos la alineaci\u00f3n de la final del Catar \u20182022 y la comparamos con la formaci\u00f3n tipo de Scaloni en este Mundial de 2026, vemos que hay muy pocas diferencias en cuanto a hombres, pero alguna muy significativa en lo que \u00e9sta conlleva a efectos de la ejecuci\u00f3n final. La defensa es exactamente la misma, con el \u00fanico cambio de la entrada de Lisandro Mart\u00ednez por Nicol\u00e1s Otamendi en el centro de la defensa y tres de los hombres de mediocampo tambi\u00e9n repiten \u2013 Rodrigo de Paul, Alexis McAllister y Leandro Paredes &#8211; pero, y aqu\u00ed viene la gran diferencia, en Catar \u20182022 el cuarto integrante del mediocampo \u2013 o tercer delantero en fase de ataque -, era \u00c1ngel di Mar\u00eda, un jugador con un perfil mucho m\u00e1s regateador y encarador de sus compa\u00f1eros de l\u00ednea y un perfil que no tiene esta Argentina actual\u2026 o solo lo tiene en las figuras de Giuliano Simeone (que solo ha sido utilizado como titular por Scaloni en el \u00faltimo partido de la fase de grupos frente a Jordania, con todo ya decidido, y en las semifinales frente a Inglaterra) o de Nico Gonz\u00e1lez, \u00fanicamente utilizado como revulsivo y no siempre en mediocampo sino como tambi\u00e9n como lateral izquierdo. Y, por completar la comparativa, en la delantera tambi\u00e9n repiten Leo Messi y Juli\u00e1n \u00c1lvarez o Lautaro Mart\u00ednez, aunque en Catar fue m\u00e1s titular el primero y en M\u00e9xico, Canad\u00e1 y USA, la cuesti\u00f3n est\u00e1 bastante m\u00e1s repartida, con el del Atl\u00e9tico de Madrid apareciendo m\u00e1s en las rondas eliminatorias que el del Inter de Mil\u00e1n.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/mitribunafutbolera.com\/wp-content\/uploads\/2026\/07\/Argentina-Catar-2022-1024x576.jpg\" alt=\"\" class=\"wp-image-1071\" srcset=\"https:\/\/mitribunafutbolera.com\/wp-content\/uploads\/2026\/07\/Argentina-Catar-2022-1024x576.jpg 1024w, https:\/\/mitribunafutbolera.com\/wp-content\/uploads\/2026\/07\/Argentina-Catar-2022-300x169.jpg 300w, https:\/\/mitribunafutbolera.com\/wp-content\/uploads\/2026\/07\/Argentina-Catar-2022-768x432.jpg 768w, https:\/\/mitribunafutbolera.com\/wp-content\/uploads\/2026\/07\/Argentina-Catar-2022-80x45.jpg 80w, https:\/\/mitribunafutbolera.com\/wp-content\/uploads\/2026\/07\/Argentina-Catar-2022.jpg 1296w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Argentina, durante el Mundial de Catar &#8216;2022<\/figcaption><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">Yendo un poco m\u00e1s al detalle, esta Argentina tiene un centro de la defensa bastante solvente \u2013 si bien a Lisandro Mart\u00ednez le falta altura (1,75 m) para ser un central dominante en el juego a\u00e9reo \u2013 y que flaquea bastante en los laterales, en el derecho, sobre todo, con Nahuel Molina: el gol de Anthony Gordon para Inglaterra en las semifinales es un ejemplo perfecto de lo que no debe hacer un lateral, perdiendo de manera grosera la posici\u00f3n y la marca de su rival.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Y, en mediocampo, viene la mayor diferencia de esta Argentina y la que le est\u00e1 causando mayores problemas de creaci\u00f3n de juego y de intimidaci\u00f3n del rival: la ausencia de un regateador, la ausencia del rol que representaba \u00c1ngel di Mar\u00eda hasta el Mundial 2022. Comenz\u00f3 Lionel Scaloni este Mundial de 2026 tratando de transponer el esquema de Catar situando a Thiago Almada como tercer delantero en la posici\u00f3n de di Mar\u00eda y manteniendo al tr\u00edo citado \u2013 Enzo Fern\u00e1ndez, de Paul y McAllister &#8211; en mediocampo; pero el pobre rendimiento de Almada hizo que, para las rondas finales, introdujese un cuarto mediocentro, Leandro Paredes, para conformar, definitivamente, un cuarteto en mediocampo. Pero, en cualquiera de los dos casos \u2013 con Almada o un cuarto centrocampista puro -, el problema es similar: acumulaci\u00f3n de perfiles en mediocampo que tienen tendencia a la zona central y ausencia de jugadores espec\u00edficos de banda: si bien Paredes o McAllister (m\u00e1s posicionales y pivotes, sobre todo, el primero), de Paul (m\u00e1s pasador), Enzo Fern\u00e1ndez (m\u00e1s box-to-box o \u2018rompedor\u2019 de l\u00edneas) o Thiago Almada (m\u00e1s mediapunta) tienen caracter\u00edsticas diferentes y algunos parten, en esta selecci\u00f3n de Scaloni, de posiciones m\u00e1s \u201clateralizadas\u201d, todos tienen tendencia a acabar confluyendo \u201cen el centro del centro del campo\u201d, privando as\u00ed al equipo de fluidez y de las alternativas en ataque que podr\u00eda aportar un regateador puro.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pero, pese a todos los pesares se\u00f1alados y al a\u00f1adido que Messi est\u00e1 poco acompa\u00f1ado en la faceta goleadora \u2013 Lautaro ha marcado tres goles y Juli\u00e1n \u00c1lvarez, apenas uno (espectacular, dicho sea de paso) &#8211; Argentina ha llegado hasta esta final guiada por el propio Messi, una vez m\u00e1s, en un rol estelar, batiendo unos r\u00e9cords que lo elevan, todav\u00eda m\u00e1s, a la categor\u00eda de mito y abrazada a una confianza y a un car\u00e1cter que hace que el equipo no desfallezca hasta el pitido final. Y, como prueba, solo quedar\u00eda darse una vuelta por Cabo Verde, Egipto, Suiza o Inglaterra.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"775\" height=\"561\" src=\"https:\/\/mitribunafutbolera.com\/wp-content\/uploads\/2026\/07\/Massi-Mundial-2026-1.png\" alt=\"\" class=\"wp-image-1073\" srcset=\"https:\/\/mitribunafutbolera.com\/wp-content\/uploads\/2026\/07\/Massi-Mundial-2026-1.png 775w, https:\/\/mitribunafutbolera.com\/wp-content\/uploads\/2026\/07\/Massi-Mundial-2026-1-300x217.png 300w, https:\/\/mitribunafutbolera.com\/wp-content\/uploads\/2026\/07\/Massi-Mundial-2026-1-768x556.png 768w, https:\/\/mitribunafutbolera.com\/wp-content\/uploads\/2026\/07\/Massi-Mundial-2026-1-80x58.png 80w\" sizes=\"auto, (max-width: 775px) 100vw, 775px\" \/><figcaption class=\"wp-element-caption\">Leo Messi, m\u00e1ximo goleador de la historia de las Copas del Mundo y gran esperanza argentina<\/figcaption><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">P.D.: En clave Espa\u00f1a, una de las claves (valga la redundancia) de la final puede estar en juntar bien las l\u00edneas, tal y como hizo ante Francia y su arsenal ofensivo, para evitar que Messi o alg\u00fan medio que se incorpore pueda flotar entre l\u00edneas y crear peligro. Valga como prueba que el gran error de Inglaterra en los minutos finales de la semifinal no fue tanto el acumular centrales y privar al equipo de alternativas para salir al ataque en transiciones, sino dejar esos huecos entre l\u00edneas que aprovech\u00f3 Messi, como parec\u00eda f\u00e1cil pronosticar, para dar dos asistencias de gol a Enzo Fern\u00e1ndez y Lautaro Mart\u00ednez.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">NOTA del AUTOR: Escrito para @VAVELesp, <a href=\"https:\/\/www.vavel.com\/es\/futbol-internacional\/2026\/07\/17\/1266017-argentina-encomendada-a-su-caracter-y-a-messi.html\">Argentina, encomendada a su car\u00e1cter y a Messi para la final del Mundial 2026 &#8211; VAVEL Espa\u00f1a<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Llega Argentina a esta final ante Espa\u00f1a habiendo dejado muchas dudas en su juego, pese a haber tenido un camino que se puede considerar como bastante asequible; de hecho, es&hellip; <\/p>\n","protected":false},"author":3,"featured_media":1070,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[328,416,375],"tags":[432,435,434],"class_list":["post-1068","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-futbol-internacional","category-mundial-2026","category-mundiales-fifa","tag-leo-messi","tag-lionel-scaloni","tag-seleccion-argentina-de-futbol"],"rise-blocks_total_comments":0,"rise-blocks_categories":[{"term_id":328,"name":"F\u00fatbol Internacional","slug":"futbol-internacional","term_group":0,"term_taxonomy_id":328,"taxonomy":"category","description":"","parent":0,"count":18,"filter":"raw","cat_ID":328,"category_count":18,"category_description":"","cat_name":"F\u00fatbol Internacional","category_nicename":"futbol-internacional","category_parent":0},{"term_id":416,"name":"Mundial '2026","slug":"mundial-2026","term_group":0,"term_taxonomy_id":416,"taxonomy":"category","description":"","parent":375,"count":8,"filter":"raw","cat_ID":416,"category_count":8,"category_description":"","cat_name":"Mundial '2026","category_nicename":"mundial-2026","category_parent":375},{"term_id":375,"name":"Mundiales FIFA","slug":"mundiales-fifa","term_group":0,"term_taxonomy_id":375,"taxonomy":"category","description":"","parent":0,"count":9,"filter":"raw","cat_ID":375,"category_count":9,"category_description":"","cat_name":"Mundiales FIFA","category_nicename":"mundiales-fifa","category_parent":0}],"rise-blocks_excerpt":"Llega Argentina a esta final ante Espa\u00f1a habiendo dejado muchas dudas en su juego, pese a haber tenido un camino que se puede considerar como bastante asequible; de hecho, es..","jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/mitribunafutbolera.com\/wp-content\/uploads\/2026\/07\/Messi-y-Scaloni.png","_links":{"self":[{"href":"https:\/\/mitribunafutbolera.com\/index.php\/wp-json\/wp\/v2\/posts\/1068","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mitribunafutbolera.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mitribunafutbolera.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mitribunafutbolera.com\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/mitribunafutbolera.com\/index.php\/wp-json\/wp\/v2\/comments?post=1068"}],"version-history":[{"count":3,"href":"https:\/\/mitribunafutbolera.com\/index.php\/wp-json\/wp\/v2\/posts\/1068\/revisions"}],"predecessor-version":[{"id":1074,"href":"https:\/\/mitribunafutbolera.com\/index.php\/wp-json\/wp\/v2\/posts\/1068\/revisions\/1074"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mitribunafutbolera.com\/index.php\/wp-json\/wp\/v2\/media\/1070"}],"wp:attachment":[{"href":"https:\/\/mitribunafutbolera.com\/index.php\/wp-json\/wp\/v2\/media?parent=1068"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mitribunafutbolera.com\/index.php\/wp-json\/wp\/v2\/categories?post=1068"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mitribunafutbolera.com\/index.php\/wp-json\/wp\/v2\/tags?post=1068"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}